{"id":774,"date":"2019-02-07T07:27:04","date_gmt":"2019-02-07T03:27:04","guid":{"rendered":"https:\/\/consdubai.esteri.it\/news\/dal_consolato\/2019\/02\/elezione-del-presidente-e-del-consiglio\/"},"modified":"2019-02-07T07:27:04","modified_gmt":"2019-02-07T03:27:04","slug":"elezione-del-presidente-e-del-consiglio","status":"publish","type":"post","link":"https:\/\/consdubai.esteri.it\/it\/news\/dal_consolato\/2019\/02\/elezione-del-presidente-e-del-consiglio\/","title":{"rendered":"Elezione del Presidente e del Consiglio della Regione Sardegna. Domenica 24 febbraio 2019. Agevolazioni per gli elettori."},"content":{"rendered":"<p>Si informa che l&#8217;AISCAT (Associazione Italiana Societa&#8217; Concessionarie Autostrade e Trafori) ha dato comunicazione della concessione agli elettori italiani residenti all&#8217;estero di agevolazioni sui pedaggi autostradali.<\/p>\n<p><a href=\"https:\/\/drive.google.com\/open?id=1xh8RxxI2n9BAO3NMG8jvkUuzFk0Ndwnm\">Nota della societa&#8217; Aiscat<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Si informa che l&#8217;AISCAT (Associazione Italiana Societa&#8217; Concessionarie Autostrade e Trafori) ha dato comunicazione della concessione agli elettori italiani residenti all&#8217;estero di agevolazioni sui pedaggi autostradali. Nota della societa&#8217; Aiscat","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-774","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consdubai.esteri.it\/it\/wp-json\/wp\/v2\/posts\/774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consdubai.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consdubai.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consdubai.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consdubai.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=774"}],"version-history":[{"count":0,"href":"https:\/\/consdubai.esteri.it\/it\/wp-json\/wp\/v2\/posts\/774\/revisions"}],"wp:attachment":[{"href":"https:\/\/consdubai.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=774"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consdubai.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}